{"id":29900,"date":"2022-08-15T16:34:03","date_gmt":"2022-08-15T16:34:03","guid":{"rendered":"https:\/\/boombattlebar.com\/uk\/stevenage\/?page_id=29900"},"modified":"2023-11-02T17:27:03","modified_gmt":"2023-11-02T17:27:03","slug":"thank-you-for-your-booking","status":"publish","type":"page","link":"https:\/\/boombattlebar.com\/uk\/stevenage\/thank-you-for-your-booking\/","title":{"rendered":"Thank you for your booking"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":15,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"templates\/template-flexible.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-29900","page","type-page","status-publish","hentry"],"acf":{"custom_schema_json":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Thank you for your booking - Stevenage<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thank you for your booking - Stevenage\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boombattlebar.com\/uk\/stevenage\/thank-you-for-your-booking\/\" \/>\n<meta property=\"og:site_name\" content=\"Stevenage\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-02T17:27:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boombattlebar.com\\\/uk\\\/stevenage\\\/thank-you-for-your-booking\\\/\",\"url\":\"https:\\\/\\\/boombattlebar.com\\\/uk\\\/stevenage\\\/thank-you-for-your-booking\\\/\",\"name\":\"Thank you for your booking - Stevenage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boombattlebar.com\\\/uk\\\/stevenage\\\/#website\"},\"datePublished\":\"2022-08-15T16:34:03+00:00\",\"dateModified\":\"2023-11-02T17:27:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boombattlebar.com\\\/uk\\\/stevenage\\\/thank-you-for-your-booking\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boombattlebar.com\\\/uk\\\/stevenage\\\/thank-you-for-your-booking\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boombattlebar.com\\\/uk\\\/stevenage\\\/thank-you-for-your-booking\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/boombattlebar.com\\\/uk\\\/stevenage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Thank you for your booking\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boombattlebar.com\\\/uk\\\/stevenage\\\/#website\",\"url\":\"https:\\\/\\\/boombattlebar.com\\\/uk\\\/stevenage\\\/\",\"name\":\"Stevenage\",\"description\":\"Just another Boom Battle Bar Network site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boombattlebar.com\\\/uk\\\/stevenage\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Thank you for your booking - Stevenage","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"Thank you for your booking - Stevenage","og_url":"https:\/\/boombattlebar.com\/uk\/stevenage\/thank-you-for-your-booking\/","og_site_name":"Stevenage","article_modified_time":"2023-11-02T17:27:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/boombattlebar.com\/uk\/stevenage\/thank-you-for-your-booking\/","url":"https:\/\/boombattlebar.com\/uk\/stevenage\/thank-you-for-your-booking\/","name":"Thank you for your booking - Stevenage","isPartOf":{"@id":"https:\/\/boombattlebar.com\/uk\/stevenage\/#website"},"datePublished":"2022-08-15T16:34:03+00:00","dateModified":"2023-11-02T17:27:03+00:00","breadcrumb":{"@id":"https:\/\/boombattlebar.com\/uk\/stevenage\/thank-you-for-your-booking\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boombattlebar.com\/uk\/stevenage\/thank-you-for-your-booking\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/boombattlebar.com\/uk\/stevenage\/thank-you-for-your-booking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/boombattlebar.com\/uk\/stevenage\/"},{"@type":"ListItem","position":2,"name":"Thank you for your booking"}]},{"@type":"WebSite","@id":"https:\/\/boombattlebar.com\/uk\/stevenage\/#website","url":"https:\/\/boombattlebar.com\/uk\/stevenage\/","name":"Stevenage","description":"Just another Boom Battle Bar Network site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boombattlebar.com\/uk\/stevenage\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"custom_schema_json":"","_links":{"self":[{"href":"https:\/\/boombattlebar.com\/uk\/stevenage\/wp-json\/wp\/v2\/pages\/29900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boombattlebar.com\/uk\/stevenage\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/boombattlebar.com\/uk\/stevenage\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/boombattlebar.com\/uk\/stevenage\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/boombattlebar.com\/uk\/stevenage\/wp-json\/wp\/v2\/comments?post=29900"}],"version-history":[{"count":1,"href":"https:\/\/boombattlebar.com\/uk\/stevenage\/wp-json\/wp\/v2\/pages\/29900\/revisions"}],"predecessor-version":[{"id":30452,"href":"https:\/\/boombattlebar.com\/uk\/stevenage\/wp-json\/wp\/v2\/pages\/29900\/revisions\/30452"}],"wp:attachment":[{"href":"https:\/\/boombattlebar.com\/uk\/stevenage\/wp-json\/wp\/v2\/media?parent=29900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}